{"id":8331,"date":"2025-02-03T18:46:12","date_gmt":"2025-02-03T23:46:12","guid":{"rendered":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/?p=8331"},"modified":"2025-02-03T18:46:12","modified_gmt":"2025-02-03T23:46:12","slug":"cinco-inmigrantes-ilegales-en-port-st-lucie-enfrentan-cargos-de-negligencia-infantil","status":"publish","type":"post","link":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/cinco-inmigrantes-ilegales-en-port-st-lucie-enfrentan-cargos-de-negligencia-infantil\/","title":{"rendered":"Cinco inmigrantes ilegales en Port St. Lucie enfrentan cargos de negligencia infantil"},"content":{"rendered":"<div class=\"mdp-speaker-wrapper\">\n            \n            \n            \n            \n            <div class=\"mdp-speaker-box mdp-speaker-box before-content speaker-wavesurfer\">\n                <div class=\"mdp-speaker-player\"  data-title=\"Cinco inmigrantes ilegales en Port St. Lucie enfrentan cargos de negligencia infantil\" data-author=\"4\" data-thumbnail=\"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2025\/02\/PSL-POLICE.jpeg\" data-type=\"speaker-wavesurfer\" data-id=\"8331\" data-src=\"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/speaker\/post-8331.mp3?cb=1738626379.mp3\" data-download=\"1\" data-speeds=\"0.5,0.75,1,1.25,1.5\" data-share=\"\" >\n                    <div class=\"mdp-speaker-wavesurfer-player mdp-speaker-wavesurfer-placeholder\"><\/div>\n                <\/div>\n            <\/div>\n            \n            \n            \n            \n\t\t\t<\/div><p>PORT ST. LUCIE, Fla. \u2014 Un infante que deambulaba solo por una calle, en Port St. Lucie, llev\u00f3 a la detenci\u00f3n de cinco inmigrantes ilegales guatemaltecos a enfrentar cargos de negligencia infantil, seg\u00fan dijo la polic\u00eda de Port St. Lucie.<\/p>\n<p>Seg\u00fan la polic\u00eda, el viernes aproximadamente a las 2:20 de que un peque de aproximadamente 1 a\u00f1o de edad estaba caminando solo por la mitad de la calle.<\/p>\n<p>La polic\u00eda dijo que desconoc\u00eda el tiempo que el menor estuvo deambulado por el vecindario, cuando al fin localizaron la casa donde resid\u00eda en la cuadra 500 de Southwest Sara Boulevard.<\/p>\n<p>Cuando las autoridades se personaron en la vivienda, en ella se encontraban Ofelia Ch\u00e1vez de 20 a\u00f1os, su pareja Edison Edilberto de 21, a\u00f1os y su hermano Estiven Hidalgo de 24 a\u00f1os. La madre del ni\u00f1o, que se encontraba en un dormitorio alimentando a una bebe de 4 meses de nacida y Edilberto e Hidalgo, se supon\u00edan estuvieran a cargo del peque\u00f1o, que sali\u00f3 por una puerta corredera en la parte trasera de la casa.<\/p>\n<p>Durante la investigaci\u00f3n la polic\u00eda hall\u00f3 que no hab\u00eda electricidad en la vivienda y en el refrigerador y el congelador hab\u00eda alimentos en descomposici\u00f3n, al parecer los ni\u00f1os dorm\u00edan en colchones en el suelo.<\/p>\n<p>Los menores fueron trasladados al hospital para ser examinados junto con un ni\u00f1o de 7 a\u00f1os, que viv\u00eda en la casa,\u00a0 que lleg\u00f3 en eses momento de la escuela con Edwin Carbajal de 26 a\u00f1os y Dais Hern\u00e1ndez de 23 a\u00f1os, que seg\u00fan explicaron\u00a0 estaban encargados de transportar el ni\u00f1o a la escuela y llevarlos de nuevo a la casa. Los ni\u00f1os no mostraban s\u00edntomas de abuso f\u00edsico, aunque con s\u00edntomas de deshidrataci\u00f3n y letargo.<\/p>\n<p>Todos los ni\u00f1os se encuentran bajo el Cuidado del Departamento de Ni\u00f1os y Familias.<\/p>\n<p>Los detenidos\u00a0 enfrentan cargos de negligencia infantil, se encuentran en la c\u00e1rcel del Condado St. Lucie sin fianza, bajo el control del Servicio de Inmigraci\u00f3n y Control de Aduanas de los Estados Unidos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PORT ST. LUCIE, Fla. \u2014 Un infante que deambulaba solo por una calle, en Port St. Lucie, llev\u00f3 a la detenci\u00f3n de cinco inmigrantes ilegales guatemaltecos a enfrentar cargos de negligencia infantil, seg\u00fan dijo la polic\u00eda de Port St. Lucie. Seg\u00fan la polic\u00eda, el viernes aproximadamente a las 2:20 de que un peque de aproximadamente &hellip;<\/p>\n","protected":false},"author":4,"featured_media":8332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[76,47,31,239],"tags":[],"coauthors":[42],"class_list":["post-8331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-condado-st-lucie-costa-del-tesoro","category-costa-del-tesoro","category-noticias-locales","category-port-saint-lucie"],"aioseo_notices":[],"image_feature":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2025\/02\/PSL-POLICE.jpeg","author_name":"Mirta Luaces","jetpack_featured_media_url":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2025\/02\/PSL-POLICE.jpeg","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/8331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/comments?post=8331"}],"version-history":[{"count":1,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/8331\/revisions"}],"predecessor-version":[{"id":8333,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/8331\/revisions\/8333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/media\/8332"}],"wp:attachment":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/media?parent=8331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/categories?post=8331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/tags?post=8331"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/coauthors?post=8331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}