{"id":3593,"date":"2023-12-18T11:10:23","date_gmt":"2023-12-18T16:10:23","guid":{"rendered":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/?p=3593"},"modified":"2023-12-18T11:11:35","modified_gmt":"2023-12-18T16:11:35","slug":"hallan-culpables-a-duena-de-escuela-de-enfermeria-en-pbc-por-emitir-diplomas-falsos","status":"publish","type":"post","link":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/hallan-culpables-a-duena-de-escuela-de-enfermeria-en-pbc-por-emitir-diplomas-falsos\/","title":{"rendered":"Hallan culpable a due\u00f1a de escuela de enfermeria en PBC por emitir diplomas falsos"},"content":{"rendered":"<div class=\"mdp-speaker-wrapper\">\n            \n            \n            \n            \n            <div class=\"mdp-speaker-box mdp-speaker-box before-content speaker-wavesurfer\">\n                <div class=\"mdp-speaker-player\"  data-title=\"Hallan culpable a due\u00f1a de escuela de enfermeria en PBC por emitir diplomas falsos\" data-author=\"4\" data-thumbnail=\"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2023\/12\/Nurse-School.jpg\" data-type=\"speaker-wavesurfer\" data-id=\"3593\" data-src=\"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/speaker\/post-3593.mp3?cb=1702915880.mp3\" data-download=\"1\" data-speeds=\"0.5,0.75,1,1.25,1.5\" data-share=\"\" >\n                    <div class=\"mdp-speaker-wavesurfer-player mdp-speaker-wavesurfer-placeholder\"><\/div>\n                <\/div>\n            <\/div>\n            \n            \n            \n            \n\t\t\t<\/div><p>FORT LAUDERDALE, Fla. \u2014 Despu\u00e9s de un juicio de tres semanas, tres personas ligadas a la emisi\u00f3n de licencias ilegales de la desaparecida escuela Palm Beach School of Nursing fueron halladas culpables en la Corte de Distrito del Sur de la Florida.<\/p>\n<p>Los jurados, el viernes, hallaron culpables de fraude electr\u00f3nico, conspiraci\u00f3n para cometer fraude electr\u00f3nico a Gail Russ, secretaria en la escuela de Lake Worth Beach, dos reclutadoras, Cassandre Jean, propietaria y operadora de Success Nursing Review en Brooklyn, Nueva York y Vilaire Durosea propietaria y operadora del Center for Advance Training and Studies en West Orange, New Jersey.<\/p>\n<p>El juez Raag Singhal de la corte de distrito fijo la fecha para la sentencia el 4 de abril a las 10 a.m. y enfrentan una condena hasta de 20 a\u00f1os de c\u00e1rcel.<\/p>\n<p>Las tres fueron encausadas con 11 coacusados, por su participaci\u00f3n en un plan, diplomas y expedientes acad\u00e9micos de enfermer\u00eda fraudulentos obtenidos de dos escuelas de enfermeras privadas, la Escuela de Enfermer\u00eda del Condado Palm Beach que estaba asociada con la Escuela de Enfermer\u00eda de Quisqueya.<\/p>\n<p>M\u00e1s de 7,600 diplomas falsos de enfermeras fueron emitidos por Palm Beach School of Nursing y Quisqueya School of Nursing LLC.<\/p>\n<p>Las escuelas fueron aprobadas por el Estado de la Florida, para emitir los diplomas y los expedientes acad\u00e9micos a personas que buscaban licencias y trabajos, como enfermeras registradas y enfermeras pr\u00e1cticas\/vocacionales con licencia, los diplomas y expedientes acad\u00e9micos calificaban a los compradores para presentarse al examen de la junta nacional de enfermer\u00eda y despu\u00e9s de aprobarlo para obtener licencias y empleo en varios estados como RN y LPN\/VN.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FORT LAUDERDALE, Fla. \u2014 Despu\u00e9s de un juicio de tres semanas, tres personas ligadas a la emisi\u00f3n de licencias ilegales de la desaparecida escuela Palm Beach School of Nursing fueron halladas culpables en la Corte de Distrito del Sur de la Florida. Los jurados, el viernes, hallaron culpables de fraude electr\u00f3nico, conspiraci\u00f3n para cometer fraude &hellip;<\/p>\n","protected":false},"author":4,"featured_media":3597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20],"tags":[252],"coauthors":[42],"class_list":["post-3593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-enfermeria"],"aioseo_notices":[],"image_feature":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2023\/12\/Nurse-School.jpg","author_name":"Mirta Luaces","jetpack_featured_media_url":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2023\/12\/Nurse-School.jpg","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/3593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/comments?post=3593"}],"version-history":[{"count":2,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/3593\/revisions"}],"predecessor-version":[{"id":3599,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/3593\/revisions\/3599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/media\/3597"}],"wp:attachment":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/media?parent=3593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/categories?post=3593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/tags?post=3593"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/coauthors?post=3593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}