{"id":17853,"date":"2026-07-15T14:47:42","date_gmt":"2026-07-15T18:47:42","guid":{"rendered":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/?p=17853"},"modified":"2026-07-15T14:47:42","modified_gmt":"2026-07-15T18:47:42","slug":"empleado-es-acusado-de-robar-mas-de-100000-en-equipos-de-jardineria-en-palm-beach-county","status":"publish","type":"post","link":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/empleado-es-acusado-de-robar-mas-de-100000-en-equipos-de-jardineria-en-palm-beach-county\/","title":{"rendered":"Empleado es acusado de robar m\u00e1s de $100,000 en equipos de jardiner\u00eda en Palm Beach County"},"content":{"rendered":"<div class=\"mdp-speaker-wrapper\">\n            \n            \n            \n            \n            <div class=\"mdp-speaker-box mdp-speaker-box before-content speaker-wavesurfer\">\n                <div class=\"mdp-speaker-player\"  data-title=\"Empleado es acusado de robar m\u00e1s de $100,000 en equipos de jardiner\u00eda en Palm Beach County\" data-author=\"4\" data-thumbnail=\"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2026\/07\/Copy-of-Template-1200-800-x-500-px-Instagram-Post-45.png\" data-type=\"speaker-wavesurfer\" data-id=\"17853\" data-src=\"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/speaker\/post-17853.mp3?cb=1784141268.mp3\" data-download=\"1\" data-speeds=\"0.5,0.75,1,1.25,1.5\" data-share=\"\" >\n                    <div class=\"mdp-speaker-wavesurfer-player mdp-speaker-wavesurfer-placeholder\"><\/div>\n                <\/div>\n            <\/div>\n            \n            \n            \n            \n\t\t\t<\/div><div class=\"relative basis-auto flex-col -mb-(--composer-overlap-px) pb-(--composer-overlap-px) [--composer-overlap-px:28px] grow flex\" data-voice-floating-orb-focus-background=\"\">\n<div class=\"flex flex-col text-sm\">\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-WEB:b034ce42-cd5d-46e6-b984-e7b5cef1fe5d-0\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:b034ce42-cd5d-46e6-b984-e7b5cef1fe5d-0\" data-turn-id-container=\"request-WEB:b034ce42-cd5d-46e6-b984-e7b5cef1fe5d-0\" data-testid=\"conversation-turn-2\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-15 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"2db6e6f2-8c09-477d-aaa0-64ec8f2d6801\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"296\" data-end=\"575\"><strong data-start=\"296\" data-end=\"327\">CONDADO DE PALM BEACH, Florida.<\/strong> \u2014 Un hombre de Riviera Beach fue arrestado tras ser acusado de sustraer un cami\u00f3n, un remolque y equipos de una empresa de jardiner\u00eda con un valor superior a los <strong>$100,000 d\u00f3lares<\/strong>, inform\u00f3 la Oficina del Sheriff del Condado de Palm Beach (PBSO).<\/p>\n<p data-start=\"577\" data-end=\"827\">El detenido fue identificado como <strong data-start=\"611\" data-end=\"631\">Jarkevius Rogers<\/strong>, de 36 a\u00f1os, quien fue arrestado el <strong data-start=\"668\" data-end=\"683\">14 de julio<\/strong> y enfrenta m\u00faltiples cargos por delitos graves, entre ellos <strong data-start=\"744\" data-end=\"826\">robo con allanamiento (burglary), hurto mayor y robo de un veh\u00edculo motorizado<\/strong>.<\/p>\n<p data-start=\"829\" data-end=\"1184\">De acuerdo con la investigaci\u00f3n, empleados de la compa\u00f1\u00eda descubrieron el <strong data-start=\"903\" data-end=\"918\">13 de julio<\/strong> que un cami\u00f3n de trabajo y un remolque cerrado hab\u00edan desaparecido del \u00e1rea de almacenamiento de la empresa. En el interior del remolque se encontraban cortadoras de c\u00e9sped, sopladoras, podadoras de setos y otras herramientas utilizadas para trabajos de jardiner\u00eda.<\/p>\n<p data-start=\"1186\" data-end=\"1371\">Los detectives utilizaron datos de <strong data-start=\"1221\" data-end=\"1228\">GPS<\/strong> para localizar el cami\u00f3n y el remolque en Riviera Beach. Aunque ambos veh\u00edculos fueron recuperados, gran parte del equipo hab\u00eda sido retirado.<\/p>\n<p data-start=\"1373\" data-end=\"1709\">Posteriormente, los investigadores localizaron la mayor parte de las herramientas robadas en una propiedad ubicada en <strong data-start=\"1491\" data-end=\"1511\">West 26th Street<\/strong>. La investigaci\u00f3n incluy\u00f3 el an\u00e1lisis de videos de vigilancia, registros del sistema GPS y c\u00e1maras de seguridad de la zona, elementos que permitieron identificar a Rogers como principal sospechoso.<\/p>\n<p data-start=\"1711\" data-end=\"2019\">Seg\u00fan el informe de arresto, Rogers <strong data-start=\"1747\" data-end=\"1785\">trabajaba para la empresa afectada<\/strong>, y el propietario logr\u00f3 reconocerlo en las im\u00e1genes captadas por las c\u00e1maras de vigilancia. Adem\u00e1s, los detectives vincularon un veh\u00edculo asociado al sospechoso con el lugar donde presuntamente fueron descargados los equipos robados.<\/p>\n<p data-start=\"2021\" data-end=\"2266\">Durante el interrogatorio, Rogers neg\u00f3 haber participado en el robo del cami\u00f3n y de las herramientas. Sin embargo, fue arrestado sin incidentes y trasladado a la <strong data-start=\"2183\" data-end=\"2219\">C\u00e1rcel del Condado de Palm Beach<\/strong>, donde permanece a disposici\u00f3n de la justicia.<\/p>\n<p data-start=\"2268\" data-end=\"2447\" data-is-last-node=\"\" data-is-only-node=\"\">Las autoridades contin\u00faan con la investigaci\u00f3n para determinar si existen otras personas involucradas en el caso y para recuperar cualquier equipo que a\u00fan permanezca desaparecido.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CONDADO DE PALM BEACH, Florida. \u2014 Un hombre de Riviera Beach fue arrestado tras ser acusado de sustraer un cami\u00f3n, un remolque y equipos de una empresa de jardiner\u00eda con un valor superior a los $100,000 d\u00f3lares, inform\u00f3 la Oficina del Sheriff del Condado de Palm Beach (PBSO). El detenido fue identificado como Jarkevius Rogers, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":17854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[46,31],"tags":[],"coauthors":[42],"class_list":["post-17853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-condado-palm-beach","category-noticias-locales"],"aioseo_notices":[],"image_feature":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2026\/07\/Copy-of-Template-1200-800-x-500-px-Instagram-Post-45.png","author_name":"Mirta Luaces","jetpack_featured_media_url":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-content\/uploads\/sites\/2\/2026\/07\/Copy-of-Template-1200-800-x-500-px-Instagram-Post-45.png","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/17853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/comments?post=17853"}],"version-history":[{"count":1,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/17853\/revisions"}],"predecessor-version":[{"id":17855,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/posts\/17853\/revisions\/17855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/media\/17854"}],"wp:attachment":[{"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/media?parent=17853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/categories?post=17853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/tags?post=17853"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/atlantikas.com\/palm-beach-costa-del-tesoro\/wp-json\/wp\/v2\/coauthors?post=17853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}